{"id":1219,"date":"2024-03-18T16:20:35","date_gmt":"2024-03-18T15:20:35","guid":{"rendered":"https:\/\/www.nuovagalvanica.com\/site\/?page_id=1219"},"modified":"2024-03-18T16:32:51","modified_gmt":"2024-03-18T15:32:51","slug":"chrome-giii","status":"publish","type":"page","link":"https:\/\/www.nuovagalvanica.com\/site\/chrome-giii\/","title":{"rendered":"Chrome GIII"},"content":{"rendered":"\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-frssf-8486b30be7cd4feb00756e0705f2524b\">\n.avia-section.av-frssf-8486b30be7cd4feb00756e0705f2524b{\nbackground-color:#019ee3;\nbackground-image:url(https:\/\/www.nuovagalvanica.com\/site\/wp-content\/uploads\/2024\/03\/header-giii.jpg);\nbackground-repeat:no-repeat;\nbackground-position:50% 50%;\nbackground-attachment:scroll;\n}\n<\/style>\n<div id='av_section_1'  class='avia-section av-frssf-8486b30be7cd4feb00756e0705f2524b main_color avia-section-default avia-no-border-styling  avia-builder-el-0  el_before_av_one_full  avia-builder-el-first  avia-full-stretch avia-bg-style-scroll av-minimum-height av-minimum-height-custom av-height-custom  container_wrap sidebar_right'  data-section-bg-repeat='stretch' data-av_minimum_height_px='430'><div class='container av-section-cont-open' style='height:430px'><main  role=\"main\" itemprop=\"mainContentOfPage\"  class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-1219'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-jwsztdkj-d8810259039840d39ff6f40fb908917d\">\n.avia-image-container.av-jwsztdkj-d8810259039840d39ff6f40fb908917d img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-jwsztdkj-d8810259039840d39ff6f40fb908917d .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-jwsztdkj-d8810259039840d39ff6f40fb908917d av-styling-no-styling avia_animated_image av-animated-when-visible-95 fade-in avia-align-center  avia-builder-el-1  avia-builder-el-no-sibling '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img fetchpriority=\"high\" class='wp-image-827 avia-img-lazy-loading-not-827 avia_image ' src='https:\/\/www.nuovagalvanica.com\/site\/wp-content\/uploads\/2019\/10\/logo-ok.png' alt='' title='logo-ok'  height=\"300\" width=\"300\"  itemprop=\"thumbnailUrl\"  \/><\/div><\/div><\/div>\n<\/div><\/div><\/main><!-- close content main element --><\/div><\/div><div id='after_section_1'  class='main_color av_default_container_wrap container_wrap sidebar_right'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-1219'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-9hk71-0e350461f8c8e3360df213205197d4a5\">\n.flex_column.av-9hk71-0e350461f8c8e3360df213205197d4a5{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-9hk71-0e350461f8c8e3360df213205197d4a5 av_one_full  avia-builder-el-2  el_after_av_section  avia-builder-el-no-sibling  first flex_column_div av-zero-column-padding  '     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-2z9p03-7348705f4c2b62d12374a70ded303733\">\n#top .av-special-heading.av-2z9p03-7348705f4c2b62d12374a70ded303733{\npadding-bottom:10px;\n}\nbody .av-special-heading.av-2z9p03-7348705f4c2b62d12374a70ded303733 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-2z9p03-7348705f4c2b62d12374a70ded303733 .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-2z9p03-7348705f4c2b62d12374a70ded303733 av-special-heading-h2 blockquote modern-quote modern-centered  avia-builder-el-3  el_before_av_hr  avia-builder-el-first '><h2 class='av-special-heading-tag '  itemprop=\"headline\"  >CHROME GIII \u00ae <\/h2><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k1t9irv6-a30168f10d26ea9caa472e5573c90029\">\n#top .hr.av-k1t9irv6-a30168f10d26ea9caa472e5573c90029{\nmargin-top:30px;\nmargin-bottom:30px;\n}\n.hr.av-k1t9irv6-a30168f10d26ea9caa472e5573c90029 .hr-inner{\nwidth:50px;\nmax-width:45%;\n}\n<\/style>\n<div  class='hr av-k1t9irv6-a30168f10d26ea9caa472e5573c90029 hr-custom  avia-builder-el-4  el_after_av_heading  el_before_av_textblock  hr-center hr-icon-yes'><span class='hr-inner inner-border-av-border-thin'><span class=\"hr-inner-style\"><\/span><\/span><span class='av-seperator-icon avia-iconfont avia-font-entypo-fontello' data-av_icon='\ue808' data-av_iconfont='entypo-fontello' ><\/span><span class='hr-inner inner-border-av-border-thin'><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<section  class='av_textblock_section av-k1t9evfw-c3e6df6874933b201e2c6cecd18f0249 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p><strong>INTRODUZIONE:<\/strong><\/p>\n<p><strong>GIII<\/strong> \u00e8 un processo di cromatura trivalente solfato\/cloruro ibrido e fornisce depositi di cromo adatti a scopi decorativi e funzionali.<\/p>\n<p>\u00c8 stato progettato per la deposizione rapida di cromo cristallino e brillante su strati di nichel.<\/p>\n<p><strong>2.1 STANDARD DI RIFERIMENTO:<\/strong><\/p>\n<ul>\n<li>ASTM B456 &#8211; Standard Specification for Electrodeposited Coatings<\/li>\n<li>UNI EN ISO 1456:2009 \u2013 European Standard Specification for Electrodeposited Coatings<\/li>\n<li>ASTM B117 \u2013 Stalt spray test<\/li>\n<li>UNI EN ISO 9227:2017 \u2013 European standard for salt spray test<\/li>\n<li>UNI EN 248:2004 &#8211; General specification for electrodeposited coatings of Ni-Cr on sanitary tapware<\/li>\n<li>REACH 1907\/2006<\/li>\n<li>ROHS2 2011\/65\/EU<\/li>\n<li>ROHS3 2015\/863\/EU<\/li>\n<\/ul>\n<p><strong>3.1 CARATTERISTICHE PRINCIPALI:<\/strong><\/p>\n<p>Il processo <strong>GIII<\/strong> consente di ottenere depositi cristallini brillanti, con le stesse caratteristiche dei sistemi esavalenti e prestazioni migliorate sulla distribuzione del deposito.<\/p>\n<p>Esente da cromo esavalente e non richiede particolari attivazioni dello strato di nichel.<\/p>\n<p>Rapida formazione di depositi, pi\u00f9 veloce del sistema esavalente e fino a 1 \u00b5m\/min<\/p>\n<p><strong>MODALITA\u2019 DI APPLICAZIONE:<\/strong><\/p>\n<ul>\n<li>Statico ( a telaio )<\/li>\n<\/ul>\n<p><strong>SPESSORI<\/strong><\/p>\n<ul>\n<li>Da valutare con il cliente in relazione alle specifiche norme e al prodotto da rivestire<\/li>\n<\/ul>\n<p><strong>DUREZZA: <\/strong><\/p>\n<ul>\n<li>900 D.P.H.<\/li>\n<\/ul>\n<p><strong>NSS TEST:<\/strong><\/p>\n<ul>\n<li>800 ore<\/li>\n<\/ul>\n<\/div><\/section><\/p><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1219","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.nuovagalvanica.com\/site\/wp-json\/wp\/v2\/pages\/1219","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nuovagalvanica.com\/site\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.nuovagalvanica.com\/site\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.nuovagalvanica.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nuovagalvanica.com\/site\/wp-json\/wp\/v2\/comments?post=1219"}],"version-history":[{"count":3,"href":"https:\/\/www.nuovagalvanica.com\/site\/wp-json\/wp\/v2\/pages\/1219\/revisions"}],"predecessor-version":[{"id":1225,"href":"https:\/\/www.nuovagalvanica.com\/site\/wp-json\/wp\/v2\/pages\/1219\/revisions\/1225"}],"wp:attachment":[{"href":"https:\/\/www.nuovagalvanica.com\/site\/wp-json\/wp\/v2\/media?parent=1219"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}