{"id":811,"date":"2019-07-11T16:51:18","date_gmt":"2019-07-11T14:51:18","guid":{"rendered":"https:\/\/www.nuovagalvanica.com\/site\/?page_id=811"},"modified":"2026-03-26T15:26:41","modified_gmt":"2026-03-26T14:26:41","slug":"certificazioni","status":"publish","type":"page","link":"https:\/\/www.nuovagalvanica.com\/site\/certificazioni\/","title":{"rendered":"Certificazioni"},"content":{"rendered":"\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-585de7-390db189e06dd7c1b5cdab0859f1f509\">\n.avia-section.av-585de7-390db189e06dd7c1b5cdab0859f1f509{\nbackground-color:#000000;\nbackground-image:url(https:\/\/www.nuovagalvanica.com\/site\/wp-content\/uploads\/2019\/10\/certificazioni.jpg);\nbackground-repeat:no-repeat;\nbackground-position:100% 100%;\nbackground-attachment:scroll;\n}\n<\/style>\n<div id='av_section_1'  class='avia-section av-585de7-390db189e06dd7c1b5cdab0859f1f509 main_color avia-section-default avia-no-border-styling  avia-builder-el-0  el_before_av_section  avia-builder-el-first  avia-full-stretch avia-bg-style-scroll av-minimum-height av-minimum-height-custom av-height-custom  container_wrap sidebar_right'  data-section-bg-repeat='stretch' data-av_minimum_height_px='430'><div class='container av-section-cont-open' style='height:430px'><main  role=\"main\" itemprop=\"mainContentOfPage\"  class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-811'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-jwsztdkj-d8810259039840d39ff6f40fb908917d\">\n.avia-image-container.av-jwsztdkj-d8810259039840d39ff6f40fb908917d img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-jwsztdkj-d8810259039840d39ff6f40fb908917d .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-jwsztdkj-d8810259039840d39ff6f40fb908917d av-styling-no-styling avia_animated_image av-animated-when-visible-95 fade-in avia-align-center  avia-builder-el-1  avia-builder-el-no-sibling '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img fetchpriority=\"high\" class='wp-image-827 avia-img-lazy-loading-not-827 avia_image ' src='https:\/\/www.nuovagalvanica.com\/site\/wp-content\/uploads\/2019\/10\/logo-ok.png' alt='' title='logo-ok'  height=\"300\" width=\"300\"  itemprop=\"thumbnailUrl\"  \/><\/div><\/div><\/div>\n\n<\/div><\/div><\/main><!-- close content main element --><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-4vhsxj-80311fa3c02b060b4cc41665e8864717\">\n.avia-section.av-4vhsxj-80311fa3c02b060b4cc41665e8864717 .av-extra-border-element .av-extra-border-inner{\nbackground-color:#ffffff;\n}\n<\/style>\n<div id='av_section_2'  class='avia-section av-4vhsxj-80311fa3c02b060b4cc41665e8864717 main_color avia-section-huge avia-no-border-styling  avia-builder-el-2  el_after_av_section  el_before_av_button_big  avia-bg-style-scroll av-arrow-down-section container_wrap sidebar_right'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-811'><div class='entry-content-wrapper clearfix'>\n<div  class='flex_column av-42wcqv-2ff3d42e7b198cdca97a57c9f77e7eab av_one_fifth  avia-builder-el-3  el_before_av_three_fifth  avia-builder-el-first  first flex_column_div  '     ><\/div><div  class='flex_column av-4idu6v-b40a9b3fbd583048805d8f6aa19a6255 av_three_fifth  avia-builder-el-4  el_after_av_one_fifth  el_before_av_one_fifth  flex_column_div  '     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_heading-edcab049f03515ecb257aee072d66eed\">\n#top .av-special-heading.av-av_heading-edcab049f03515ecb257aee072d66eed{\npadding-bottom:10px;\n}\nbody .av-special-heading.av-av_heading-edcab049f03515ecb257aee072d66eed .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-av_heading-edcab049f03515ecb257aee072d66eed .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-av_heading-edcab049f03515ecb257aee072d66eed av-special-heading-h2 blockquote modern-quote modern-centered  avia-builder-el-5  el_before_av_hr  avia-builder-el-first '><h2 class='av-special-heading-tag '  itemprop=\"headline\"  >LE NOSTRE CERTIFICAZIONI<\/h2><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-dvvpr-b82e8c9fa848a06b6c634fc673502864\">\n#top .hr.av-dvvpr-b82e8c9fa848a06b6c634fc673502864{\nmargin-top:30px;\nmargin-bottom:47px;\n}\n.hr.av-dvvpr-b82e8c9fa848a06b6c634fc673502864 .hr-inner{\nwidth:50px;\nmax-width:45%;\n}\n.hr.av-dvvpr-b82e8c9fa848a06b6c634fc673502864 .av-seperator-icon{\ncolor:#1e73be;\n}\n.hr.av-dvvpr-b82e8c9fa848a06b6c634fc673502864 .av-seperator-icon.avia-svg-icon svg:first-child{\nfill:#1e73be;\nstroke:#1e73be;\n}\n<\/style>\n<div  class='hr av-dvvpr-b82e8c9fa848a06b6c634fc673502864 hr-custom  avia-builder-el-6  el_after_av_heading  el_before_av_textblock  hr-center hr-icon-yes'><span class='hr-inner inner-border-av-border-thin'><span class=\"hr-inner-style\"><\/span><\/span><span class='av-seperator-icon avia-iconfont avia-font-entypo-fontello' data-av_icon='\ue8b4' data-av_iconfont='entypo-fontello' ><\/span><span class='hr-inner inner-border-av-border-thin'><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-f7f4v-a4331cfec39618211aef6ef9d1f24dae\">\n#top .av_textblock_section.av-f7f4v-a4331cfec39618211aef6ef9d1f24dae .avia_textblock{\nfont-size:16px;\n}\n<\/style>\n<section  class='av_textblock_section av-f7f4v-a4331cfec39618211aef6ef9d1f24dae '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p style=\"text-align: center;\">Le certificazioni che la nostra azienda pu\u00f2 vantare:<\/p>\n<\/div><\/section><\/p><\/div><div  class='flex_column av-42wcqv-91e38971f505049e7e49db9b6064a305 av_one_fifth  avia-builder-el-8  el_after_av_three_fifth  el_before_av_one_half  flex_column_div  '     ><\/div><div  class='flex_column av-3sdd87-51052d1e106b18f59c991f22e25a075b av_one_half  avia-builder-el-9  el_after_av_one_fifth  el_before_av_one_half  first flex_column_div  column-top-margin'     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-jv26r7fz-8e8e293e0b372a7f2771c2c99a8c5268\">\n.iconbox.av-jv26r7fz-8e8e293e0b372a7f2771c2c99a8c5268 .iconbox_icon{\ncolor:#019ee3;\n}\n.iconbox.av-jv26r7fz-8e8e293e0b372a7f2771c2c99a8c5268 .iconbox_icon.avia-svg-icon svg:first-child{\nfill:#019ee3;\nstroke:#019ee3;\n}\n#top #wrap_all .iconbox.av-jv26r7fz-8e8e293e0b372a7f2771c2c99a8c5268 .iconbox_content_title{\ncolor:#019ee3;\n}\n<\/style>\n<article  class='iconbox iconbox_left av-jv26r7fz-8e8e293e0b372a7f2771c2c99a8c5268  avia-builder-el-10  avia-builder-el-no-sibling '  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconbox_content\"><header class=\"entry-content-header\" aria-label=\"Icona: Politica QHSE\"><a href='https:\/\/www.nuovagalvanica.com\/site\/wp-content\/uploads\/2026\/03\/03_POL_Politica-QHSE_rev0_2025.11.10.pdf' title='Politica QHSE' aria-label='Politica QHSE'  target=\"_blank\"  rel=\"noopener noreferrer\" class='iconbox_icon heading-color avia-iconfont avia-font-entypo-fontello' data-av_icon='\ue84b' data-av_iconfont='entypo-fontello' title=\"Politica QHSE\" desc=\"Politica QHSE\" ><\/a><h3 class='iconbox_content_title '  itemprop=\"headline\" ><a href='https:\/\/www.nuovagalvanica.com\/site\/wp-content\/uploads\/2026\/03\/03_POL_Politica-QHSE_rev0_2025.11.10.pdf' title='Politica QHSE'  target=\"_blank\"  rel=\"noopener noreferrer\">Politica QHSE<\/a><\/h3><\/header><div class='iconbox_content_container '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div><div  class='flex_column av-3sdd87-0193d1fa9a7a1bc06c2a499773b870f0 av_one_half  avia-builder-el-11  el_after_av_one_half  el_before_av_one_half  flex_column_div  column-top-margin'     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-jv26r7fz-0d2850cb4e5b95690de3e6dbfb85e84c\">\n.iconbox.av-jv26r7fz-0d2850cb4e5b95690de3e6dbfb85e84c .iconbox_icon{\ncolor:#019ee3;\n}\n.iconbox.av-jv26r7fz-0d2850cb4e5b95690de3e6dbfb85e84c .iconbox_icon.avia-svg-icon svg:first-child{\nfill:#019ee3;\nstroke:#019ee3;\n}\n#top #wrap_all .iconbox.av-jv26r7fz-0d2850cb4e5b95690de3e6dbfb85e84c .iconbox_content_title{\ncolor:#019ee3;\n}\n<\/style>\n<article  class='iconbox iconbox_left av-jv26r7fz-0d2850cb4e5b95690de3e6dbfb85e84c  avia-builder-el-12  avia-builder-el-no-sibling '  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconbox_content\"><header class=\"entry-content-header\" aria-label=\"Icona: NSF\"><a href='https:\/\/www.nuovagalvanica.com\/site\/wp-content\/uploads\/2019\/10\/certificato_NSF.pdf' title='NSF' aria-label='NSF'  target=\"_blank\"  rel=\"noopener noreferrer\" class='iconbox_icon heading-color avia-iconfont avia-font-entypo-fontello' data-av_icon='\ue84b' data-av_iconfont='entypo-fontello' title=\"NSF\" desc=\"NSF\" ><\/a><h3 class='iconbox_content_title '  itemprop=\"headline\" ><a href='https:\/\/www.nuovagalvanica.com\/site\/wp-content\/uploads\/2019\/10\/certificato_NSF.pdf' title='NSF'  target=\"_blank\"  rel=\"noopener noreferrer\">NSF<\/a><\/h3><\/header><div class='iconbox_content_container '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div><div  class='flex_column av-3fga67-cc0566faa58fafb68418ac849fb85ad7 av_one_half  avia-builder-el-13  el_after_av_one_half  avia-builder-el-last  first flex_column_div  column-top-margin'     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-jv26r7fz-aa406394726afb914a1a235793bdd6b3\">\n.iconbox.av-jv26r7fz-aa406394726afb914a1a235793bdd6b3 .iconbox_icon{\ncolor:#019ee3;\n}\n.iconbox.av-jv26r7fz-aa406394726afb914a1a235793bdd6b3 .iconbox_icon.avia-svg-icon svg:first-child{\nfill:#019ee3;\nstroke:#019ee3;\n}\n#top #wrap_all .iconbox.av-jv26r7fz-aa406394726afb914a1a235793bdd6b3 .iconbox_content_title{\ncolor:#019ee3;\n}\n<\/style>\n<article  class='iconbox iconbox_left av-jv26r7fz-aa406394726afb914a1a235793bdd6b3  avia-builder-el-14  avia-builder-el-no-sibling '  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconbox_content\"><header class=\"entry-content-header\" aria-label=\"Icona: AIA\"><a href='https:\/\/www.nuovagalvanica.com\/site\/wp-content\/uploads\/2019\/10\/certrificato_AIA.pdf' title='AIA' aria-label='AIA'  target=\"_blank\"  rel=\"noopener noreferrer\" class='iconbox_icon heading-color avia-iconfont avia-font-entypo-fontello' data-av_icon='\ue84b' data-av_iconfont='entypo-fontello' title=\"AIA\" desc=\"AIA\" ><\/a><h3 class='iconbox_content_title '  itemprop=\"headline\" ><a href='https:\/\/www.nuovagalvanica.com\/site\/wp-content\/uploads\/2019\/10\/certrificato_AIA.pdf' title='AIA'  target=\"_blank\"  rel=\"noopener noreferrer\">AIA<\/a><\/h3><\/header><div class='iconbox_content_container '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div><div  class='avia-button-wrap avia-button-center  avia-builder-el-15  el_after_av_section  avia-builder-el-last '>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-6t1bz-60fbb5e3621eaa30382c023d5ced2f2c\">\n#top #wrap_all .avia-button.av-6t1bz-60fbb5e3621eaa30382c023d5ced2f2c{\nbackground-color:#019ee3;\nborder-color:#019ee3;\ncolor:#ffffff;\ntransition:all 0.4s ease-in-out;\n}\n#top #wrap_all .avia-button.av-6t1bz-60fbb5e3621eaa30382c023d5ced2f2c:hover{\nbackground-color:#444444;\ncolor:#ffffff;\ntransition:all 0.4s ease-in-out;\n}\n#top #wrap_all .avia-button.av-6t1bz-60fbb5e3621eaa30382c023d5ced2f2c .avia-svg-icon svg:first-child{\nfill:#ffffff;\nstroke:#ffffff;\n}\n#top #wrap_all .avia-button.av-6t1bz-60fbb5e3621eaa30382c023d5ced2f2c:hover .avia-svg-icon svg:first-child{\nfill:#ffffff;\nstroke:#ffffff;\n}\n<\/style>\n<a href='https:\/\/www.nuovagalvanica.com\/site\/?page_id=467' class='av-icon-on-hover avia-button avia-button-fullwidth av-6t1bz-60fbb5e3621eaa30382c023d5ced2f2c avia-icon_select-yes-right-icon avia-color-custom'   aria-label=\"Contattaci\"><span class='avia_iconbox_title' >Contattaci<\/span><span class='avia_button_icon avia_button_icon_right avia-iconfont avia-font-entypo-fontello' data-av_icon='\ue805' data-av_iconfont='entypo-fontello' ><\/span><div class='av-button-description av-button-description-below'><p>Hai bisogno di un preventivo, di qualche informazione o semplicemente vuoi conoscerci meglio?<br \/>\nClicca qui e contattaci subito<\/p>\n<\/div><\/a><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-811","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.nuovagalvanica.com\/site\/wp-json\/wp\/v2\/pages\/811","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nuovagalvanica.com\/site\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.nuovagalvanica.com\/site\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.nuovagalvanica.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nuovagalvanica.com\/site\/wp-json\/wp\/v2\/comments?post=811"}],"version-history":[{"count":8,"href":"https:\/\/www.nuovagalvanica.com\/site\/wp-json\/wp\/v2\/pages\/811\/revisions"}],"predecessor-version":[{"id":1247,"href":"https:\/\/www.nuovagalvanica.com\/site\/wp-json\/wp\/v2\/pages\/811\/revisions\/1247"}],"wp:attachment":[{"href":"https:\/\/www.nuovagalvanica.com\/site\/wp-json\/wp\/v2\/media?parent=811"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}